{"id":2773,"date":"2023-02-03T10:51:22","date_gmt":"2023-02-03T09:51:22","guid":{"rendered":"https:\/\/imm.webs.upv.es\/?p=2773"},"modified":"2025-01-30T14:32:12","modified_gmt":"2025-01-30T13:32:12","slug":"2773-2","status":"publish","type":"post","link":"https:\/\/imm.webs.upv.es\/es\/2773-2\/","title":{"rendered":"Matem\u00e1ticas en danza"},"content":{"rendered":"\n<p>Desde el Departamento de Matem\u00e1tica Aplicada y los Institutos Universitarios de Matem\u00e1tica Multidisciplinar y Matem\u00e1tica Pura y Aplicada, junto con el Vicerrectorado de Arte, Ciencia, Tecnolog\u00eda y Sociedad de la Universitat Polit\u00e8cnica de Val\u00e8ncia:<\/p>\n\n\n\n<p>Nos complace anunciaros que&nbsp;<strong>el lunes 27 de febrero<\/strong><strong>&nbsp;a las 17:00&nbsp;<\/strong>h&nbsp;celebraremos conjuntamente, con algunos d\u00edas de adelanto, el D\u00eda Internacional de las Matem\u00e1ticas y el D\u00eda de la Mujer.<\/p>\n\n\n\n<p>Para ello, hemos organizado:<\/p>\n\n\n\n<p>MATEM\u00c1TICAS EN DANZA<\/p>\n\n\n\n<p>una actividad que incluye un espect\u00e1culo de danza en directo a cargo del Grupo de Danza Marta G\u00f3mez y la proyecci\u00f3n del cortometraje Matem\u00e1ticas en Danza presentado por el Grupo de Innovaci\u00f3n Educativa Pensamiento Matem\u00e1tico, del que pod\u00e9is ver un tr\u00e1iler<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Tr\u00e1iler con mates\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/ntqcshKRZPg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Como es f\u00e1cil de adivinar es una actividad cuyas protagonistas son las Matem\u00e1ticas, la danza y las mujeres que mayoritariamente han promovido esta actividad, capitaneadas por Maril\u00f3 L\u00f3pez, profesora de la Universidad Polit\u00e9cnica de Madrid.<\/p>\n\n\n\n<p>A partir de las 17:00 en el <strong>Hall del Paraninfo del Rectorado<\/strong> de la Universitat Polit\u00e8cnica de Val\u00e8ncia empezar\u00e1n a \u201cpasar cosas\u201d. Y a las 17:30, dentro ya del Paraninfo, se proyectar\u00e1 el cortometraje junto con actuaciones de danza en directo.<\/p>\n\n\n\n<p><strong>Esta actividad est\u00e1 abierta a todo el p\u00fablico y es adecuada para todas las edades, por lo que os animamos a participar y que invit\u00e9is tambi\u00e9n a vuestras familias y amigos.<\/strong><\/p>\n\n\n\n<p>Os esperamos,<br>Los organizadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Departamento de Matem\u00e1tica Aplicada y los Institutos Universitarios de Matem\u00e1tica Multidisciplinar y Matem\u00e1tica Pura y Aplicada, junto con el Vicerrectorado de Arte, Ciencia, Tecnolog\u00eda y Sociedad de la Universitat Polit\u00e8cnica de Val\u00e8ncia: Nos complace anunciaros que&nbsp;el lunes 27 de febrero&nbsp;a las 17:00&nbsp;h&nbsp;celebraremos conjuntamente, con algunos d\u00edas de adelanto,&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/imm.webs.upv.es\/es\/2773-2\/\">Show more<\/a><\/p>\n","protected":false},"author":4,"featured_media":2779,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-talks-seminars"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","ca","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"ca":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matem\u00e1ticas en danza - I. U. de Matem\u00e1tica Multidisciplinar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imm.webs.upv.es\/2773-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matem\u00e1ticas en danza - I. U. de Matem\u00e1tica Multidisciplinar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imm.webs.upv.es\/2773-2\/\" \/>\n<meta property=\"og:site_name\" content=\"I. U. de Matem\u00e1tica Multidisciplinar\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T09:51:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T13:32:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2023\/02\/WB_mates.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1946\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#\\\/schema\\\/person\\\/3a01efcd7e7d66b83875b866576d05f4\"},\"headline\":\"Matem\u00e1ticas en danza\",\"datePublished\":\"2023-02-03T09:51:22+00:00\",\"dateModified\":\"2025-01-30T13:32:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/\"},\"wordCount\":768,\"publisher\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/imm.webs.upv.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WB_mates.png\",\"articleSection\":[\"Charlas y seminarios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/\",\"url\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/\",\"name\":\"Matem\u00e1ticas en danza - I. U. de Matem\u00e1tica Multidisciplinar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/imm.webs.upv.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WB_mates.png\",\"datePublished\":\"2023-02-03T09:51:22+00:00\",\"dateModified\":\"2025-01-30T13:32:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/imm.webs.upv.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WB_mates.png\",\"contentUrl\":\"https:\\\/\\\/imm.webs.upv.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/WB_mates.png\",\"width\":1946,\"height\":1068,\"caption\":\"Matem\u00e1ticas en danza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/2773-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/imm.webs.upv.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mathematics in dance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#website\",\"url\":\"https:\\\/\\\/imm.webs.upv.es\\\/\",\"name\":\"I. U. de Matem\u00e1tica Multidisciplinar\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/imm.webs.upv.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#organization\",\"name\":\"I. U. de Matem\u00e1tica Multidisciplinar\",\"url\":\"https:\\\/\\\/imm.webs.upv.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/imm.webs.upv.es\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/imm_blue-1.png\",\"contentUrl\":\"https:\\\/\\\/imm.webs.upv.es\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/imm_blue-1.png\",\"width\":931,\"height\":498,\"caption\":\"I. U. de Matem\u00e1tica Multidisciplinar\"},\"image\":{\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/imm.webs.upv.es\\\/#\\\/schema\\\/person\\\/3a01efcd7e7d66b83875b866576d05f4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493534f54da39aef6ce2003bc984565871e277e5136e50eac1c5a277c4113d39?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493534f54da39aef6ce2003bc984565871e277e5136e50eac1c5a277c4113d39?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493534f54da39aef6ce2003bc984565871e277e5136e50eac1c5a277c4113d39?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/imm.webs.upv.es\\\/es\\\/author\\\/admin-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matem\u00e1ticas en danza - I. U. de Matem\u00e1tica Multidisciplinar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imm.webs.upv.es\/2773-2\/","og_locale":"es_ES","og_type":"article","og_title":"Matem\u00e1ticas en danza - I. U. de Matem\u00e1tica Multidisciplinar","og_url":"https:\/\/imm.webs.upv.es\/2773-2\/","og_site_name":"I. U. de Matem\u00e1tica Multidisciplinar","article_published_time":"2023-02-03T09:51:22+00:00","article_modified_time":"2025-01-30T13:32:12+00:00","og_image":[{"width":1946,"height":1068,"url":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2023\/02\/WB_mates.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/imm.webs.upv.es\/2773-2\/#article","isPartOf":{"@id":"https:\/\/imm.webs.upv.es\/2773-2\/"},"author":{"name":"admin","@id":"https:\/\/imm.webs.upv.es\/#\/schema\/person\/3a01efcd7e7d66b83875b866576d05f4"},"headline":"Matem\u00e1ticas en danza","datePublished":"2023-02-03T09:51:22+00:00","dateModified":"2025-01-30T13:32:12+00:00","mainEntityOfPage":{"@id":"https:\/\/imm.webs.upv.es\/2773-2\/"},"wordCount":768,"publisher":{"@id":"https:\/\/imm.webs.upv.es\/#organization"},"image":{"@id":"https:\/\/imm.webs.upv.es\/2773-2\/#primaryimage"},"thumbnailUrl":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2023\/02\/WB_mates.png","articleSection":["Charlas y seminarios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/imm.webs.upv.es\/2773-2\/","url":"https:\/\/imm.webs.upv.es\/2773-2\/","name":"Matem\u00e1ticas en danza - I. U. de Matem\u00e1tica Multidisciplinar","isPartOf":{"@id":"https:\/\/imm.webs.upv.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/imm.webs.upv.es\/2773-2\/#primaryimage"},"image":{"@id":"https:\/\/imm.webs.upv.es\/2773-2\/#primaryimage"},"thumbnailUrl":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2023\/02\/WB_mates.png","datePublished":"2023-02-03T09:51:22+00:00","dateModified":"2025-01-30T13:32:12+00:00","breadcrumb":{"@id":"https:\/\/imm.webs.upv.es\/2773-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/imm.webs.upv.es\/2773-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imm.webs.upv.es\/2773-2\/#primaryimage","url":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2023\/02\/WB_mates.png","contentUrl":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2023\/02\/WB_mates.png","width":1946,"height":1068,"caption":"Matem\u00e1ticas en danza"},{"@type":"BreadcrumbList","@id":"https:\/\/imm.webs.upv.es\/2773-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/imm.webs.upv.es\/"},{"@type":"ListItem","position":2,"name":"Mathematics in dance"}]},{"@type":"WebSite","@id":"https:\/\/imm.webs.upv.es\/#website","url":"https:\/\/imm.webs.upv.es\/","name":"I. U. de Matem\u00e1tica Multidisciplinar","description":"","publisher":{"@id":"https:\/\/imm.webs.upv.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imm.webs.upv.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/imm.webs.upv.es\/#organization","name":"I. U. de Matem\u00e1tica Multidisciplinar","url":"https:\/\/imm.webs.upv.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/imm.webs.upv.es\/#\/schema\/logo\/image\/","url":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2020\/11\/imm_blue-1.png","contentUrl":"https:\/\/imm.webs.upv.es\/wp-content\/uploads\/2020\/11\/imm_blue-1.png","width":931,"height":498,"caption":"I. U. de Matem\u00e1tica Multidisciplinar"},"image":{"@id":"https:\/\/imm.webs.upv.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/imm.webs.upv.es\/#\/schema\/person\/3a01efcd7e7d66b83875b866576d05f4","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/493534f54da39aef6ce2003bc984565871e277e5136e50eac1c5a277c4113d39?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/493534f54da39aef6ce2003bc984565871e277e5136e50eac1c5a277c4113d39?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/493534f54da39aef6ce2003bc984565871e277e5136e50eac1c5a277c4113d39?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/imm.webs.upv.es\/es\/author\/admin-2\/"}]}},"_links":{"self":[{"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/posts\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/comments?post=2773"}],"version-history":[{"count":11,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/posts\/2773\/revisions"}],"predecessor-version":[{"id":2789,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/posts\/2773\/revisions\/2789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/media\/2779"}],"wp:attachment":[{"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/media?parent=2773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/categories?post=2773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imm.webs.upv.es\/es\/wp-json\/wp\/v2\/tags?post=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}